
{"id":1404,"date":"2013-06-20T09:43:45","date_gmt":"2013-06-20T09:43:45","guid":{"rendered":"http:\/\/www.barbarasudano.net\/web\/?p=1404"},"modified":"2015-06-25T08:56:58","modified_gmt":"2015-06-25T08:56:58","slug":"chiaramonte-gulfi-4","status":"publish","type":"post","link":"http:\/\/www.barbarasudano.net\/web\/de\/chiaramonte-gulfi-4\/","title":{"rendered":"Chiaramonte Gulfi"},"content":{"rendered":"<p style=\"text-align: right;\"><em>Halbtagestour &#8211; bis zu 4 Stunden<\/em><\/p>\n<p>Die Panorama-Terrasse von Chiaramonte auf dem nordwestlichen Teil der Stadt, gegen\u00fcber der Kirche von Cappuccini, ist als der &#8222;Balkon von Sizilien&#8220; bekannt, weil es den Besuchern eine herrliche Aussicht bietet.<br \/>\n<!--more--><\/p>\n<p>Der Stadtrundgang von Chiaramonte f\u00fchrt zu den wichtigsten Sehensw\u00fcrdigkeiten der Stadt: zum offensichtlichen Garten, zur Kirche Santa Maria La Nova, zum sch\u00f6nen Bogen von Annunziata, der das Erdbeben von 1693\u00a0\u00fcberlebt hat und zur Kirche des heiligen Johannes. In Chiaramonte befinden sich zahlreiche Museen, unter anderen\u00a0das \u00d6lmuseum und das Museum der sizilianischen Handstickerei. Die Aussicht \u00a0hier ist wundersch\u00f6n! Unweit der Stadt ist der Santuario di Gulfi. Es wurde im 18. Jahrhundert erbaut und beherbergt die sch\u00f6ne Madonna mit dem Kind.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Halbtagestour &#8211; bis zu 4 Stunden Die Panorama-Terrasse von Chiaramonte auf dem nordwestlichen Teil der Stadt, gegen\u00fcber der &#8230;<a href=\"http:\/\/www.barbarasudano.net\/web\/de\/chiaramonte-gulfi-4\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":1405,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[48],"tags":[],"_links":{"self":[{"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/posts\/1404"}],"collection":[{"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/comments?post=1404"}],"version-history":[{"count":4,"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/posts\/1404\/revisions"}],"predecessor-version":[{"id":1697,"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/posts\/1404\/revisions\/1697"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/media\/1405"}],"wp:attachment":[{"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/media?parent=1404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/categories?post=1404"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.barbarasudano.net\/web\/de\/wp-json\/wp\/v2\/tags?post=1404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}